{"id":15538,"date":"2026-05-06T11:24:16","date_gmt":"2026-05-06T09:24:16","guid":{"rendered":"https:\/\/spsow.cz\/?p=15538"},"modified":"2026-05-06T11:25:41","modified_gmt":"2026-05-06T09:25:41","slug":"prvni-druhe-treti-misto-pod-lupou","status":"publish","type":"post","link":"https:\/\/spsow.cz\/en\/2026\/05\/06\/prvni-druhe-treti-misto-pod-lupou\/","title":{"rendered":"PRVN\u00cd, DRUH\u00c9, T\u0158ET\u00cd M\u00cdSTO POD LUPOU"},"content":{"rendered":"<p class=\"has-medium-font-size\">V r\u00e1mci 27. ro\u010dn\u00edku festivalu N\u00e1chodsk\u00e1 prima sez\u00f3na prob\u011bhla v\u00fdtvarn\u00e1 sout\u011b\u017e \u201ePod lupou\u201c, kter\u00e1 hledala kr\u00e1su v detailech a skryt\u00fdch v\u00fdznamech sv\u011bta kolem n\u00e1s. Na\u0161e studentky 2. ro\u010dn\u00edku oboru Grafick\u00fd design v&nbsp;kategorii st\u0159edo\u0161kol\u00e1k\u016f (16\u201318 let) zaz\u00e1\u0159ily a odnesly si v\u0161echna t\u0159i nejvy\u0161\u0161\u00ed ocen\u011bn\u00ed.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-medium-font-size\"><strong>1. m\u00edsto: Ali Zelensk\u00e1<\/strong>\u00a0s d\u00edlem \u201eFear bubble\u201c<\/li>\n\n\n\n<li class=\"has-medium-font-size\"><strong>2. m\u00edsto: Julie \u0160elepecov\u00e1<\/strong>\u00a0s d\u00edlem \u201eP\u0159ed b\u00e1lem\u201c<\/li>\n\n\n\n<li class=\"has-medium-font-size\"><strong>3. m\u00edsto: Tereza Fialov\u00e1<\/strong>\u00a0s d\u00edlem \u201eSrdce oce\u00e1nu\u201c<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size\">V\u0161echna sout\u011b\u017en\u00ed d\u00edla, kter\u00e1 zkoumaj\u00ed t\u00e9mata jako mikrosv\u011bt \u010di detaily fantazie, jsou k vid\u011bn\u00ed ve v\u00fdstavn\u00ed chodb\u011b M\u011bstsk\u00e9 knihovny v N\u00e1chod\u011b.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Ali, Julii a Terce moc gratulujeme a d\u011bkujeme za fantastickou reprezentaci na\u0161\u00ed \u0161koly!<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/0d6bab51-dd29-420f-bd0a-3e6aa04d32e9.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"15543\" src=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/0d6bab51-dd29-420f-bd0a-3e6aa04d32e9-1024x768.jpg\" alt=\"\" class=\"wp-image-15543\" srcset=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/0d6bab51-dd29-420f-bd0a-3e6aa04d32e9-1024x768.jpg 1024w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/0d6bab51-dd29-420f-bd0a-3e6aa04d32e9-300x225.jpg 300w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/0d6bab51-dd29-420f-bd0a-3e6aa04d32e9-768x576.jpg 768w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/0d6bab51-dd29-420f-bd0a-3e6aa04d32e9-1536x1152.jpg 1536w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/0d6bab51-dd29-420f-bd0a-3e6aa04d32e9-16x12.jpg 16w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/0d6bab51-dd29-420f-bd0a-3e6aa04d32e9.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/5fc7d140-7265-47d8-ba12-20a64f26a34c.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"15542\" src=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/5fc7d140-7265-47d8-ba12-20a64f26a34c-768x1024.jpg\" alt=\"\" class=\"wp-image-15542\" srcset=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/5fc7d140-7265-47d8-ba12-20a64f26a34c-768x1024.jpg 768w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/5fc7d140-7265-47d8-ba12-20a64f26a34c-225x300.jpg 225w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/5fc7d140-7265-47d8-ba12-20a64f26a34c-1152x1536.jpg 1152w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/5fc7d140-7265-47d8-ba12-20a64f26a34c-9x12.jpg 9w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/5fc7d140-7265-47d8-ba12-20a64f26a34c.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/6a476252-d7b1-47bf-88cd-358090c8ca56.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"15541\" src=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/6a476252-d7b1-47bf-88cd-358090c8ca56-1024x768.jpg\" alt=\"\" class=\"wp-image-15541\" srcset=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/6a476252-d7b1-47bf-88cd-358090c8ca56-1024x768.jpg 1024w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/6a476252-d7b1-47bf-88cd-358090c8ca56-300x225.jpg 300w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/6a476252-d7b1-47bf-88cd-358090c8ca56-768x576.jpg 768w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/6a476252-d7b1-47bf-88cd-358090c8ca56-1536x1152.jpg 1536w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/6a476252-d7b1-47bf-88cd-358090c8ca56-16x12.jpg 16w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/6a476252-d7b1-47bf-88cd-358090c8ca56.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/18ef01b1-4e0a-48b6-ae39-c1d6a50eeaa3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"15555\" src=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/18ef01b1-4e0a-48b6-ae39-c1d6a50eeaa3-1024x768.jpg\" alt=\"\" class=\"wp-image-15555\" srcset=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/18ef01b1-4e0a-48b6-ae39-c1d6a50eeaa3-1024x768.jpg 1024w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/18ef01b1-4e0a-48b6-ae39-c1d6a50eeaa3-300x225.jpg 300w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/18ef01b1-4e0a-48b6-ae39-c1d6a50eeaa3-768x576.jpg 768w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/18ef01b1-4e0a-48b6-ae39-c1d6a50eeaa3-1536x1152.jpg 1536w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/18ef01b1-4e0a-48b6-ae39-c1d6a50eeaa3-16x12.jpg 16w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/18ef01b1-4e0a-48b6-ae39-c1d6a50eeaa3.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/45e065d0-80c2-4e10-abb8-5a42fdf947c7.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"15546\" src=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/45e065d0-80c2-4e10-abb8-5a42fdf947c7-1024x768.jpg\" alt=\"\" class=\"wp-image-15546\" srcset=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/45e065d0-80c2-4e10-abb8-5a42fdf947c7-1024x768.jpg 1024w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/45e065d0-80c2-4e10-abb8-5a42fdf947c7-300x225.jpg 300w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/45e065d0-80c2-4e10-abb8-5a42fdf947c7-768x576.jpg 768w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/45e065d0-80c2-4e10-abb8-5a42fdf947c7-1536x1152.jpg 1536w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/45e065d0-80c2-4e10-abb8-5a42fdf947c7-16x12.jpg 16w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/45e065d0-80c2-4e10-abb8-5a42fdf947c7.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/63aa97d1-7645-4c38-8313-93970add1c11.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"15556\" src=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/63aa97d1-7645-4c38-8313-93970add1c11-768x1024.jpg\" alt=\"\" class=\"wp-image-15556\" srcset=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/63aa97d1-7645-4c38-8313-93970add1c11-768x1024.jpg 768w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/63aa97d1-7645-4c38-8313-93970add1c11-225x300.jpg 225w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/63aa97d1-7645-4c38-8313-93970add1c11-1152x1536.jpg 1152w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/63aa97d1-7645-4c38-8313-93970add1c11-9x12.jpg 9w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/63aa97d1-7645-4c38-8313-93970add1c11.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/67dd6e03-56f3-4d4a-90db-fe36db968ac0.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"15550\" src=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/67dd6e03-56f3-4d4a-90db-fe36db968ac0-768x1024.jpg\" alt=\"\" class=\"wp-image-15550\" srcset=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/67dd6e03-56f3-4d4a-90db-fe36db968ac0-768x1024.jpg 768w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/67dd6e03-56f3-4d4a-90db-fe36db968ac0-225x300.jpg 225w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/67dd6e03-56f3-4d4a-90db-fe36db968ac0-1152x1536.jpg 1152w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/67dd6e03-56f3-4d4a-90db-fe36db968ac0-9x12.jpg 9w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/67dd6e03-56f3-4d4a-90db-fe36db968ac0.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/542a4461-1cdd-437c-9690-ad2443a5b3bd.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"15548\" src=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/542a4461-1cdd-437c-9690-ad2443a5b3bd-768x1024.jpg\" alt=\"\" class=\"wp-image-15548\" srcset=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/542a4461-1cdd-437c-9690-ad2443a5b3bd-768x1024.jpg 768w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/542a4461-1cdd-437c-9690-ad2443a5b3bd-225x300.jpg 225w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/542a4461-1cdd-437c-9690-ad2443a5b3bd-1152x1536.jpg 1152w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/542a4461-1cdd-437c-9690-ad2443a5b3bd-9x12.jpg 9w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/542a4461-1cdd-437c-9690-ad2443a5b3bd.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/83868ba0-00ed-4397-bace-fe90a312ca15.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"15561\" src=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/83868ba0-00ed-4397-bace-fe90a312ca15-1024x768.jpg\" alt=\"\" class=\"wp-image-15561\" srcset=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/83868ba0-00ed-4397-bace-fe90a312ca15-1024x768.jpg 1024w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/83868ba0-00ed-4397-bace-fe90a312ca15-300x225.jpg 300w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/83868ba0-00ed-4397-bace-fe90a312ca15-768x576.jpg 768w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/83868ba0-00ed-4397-bace-fe90a312ca15-1536x1152.jpg 1536w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/83868ba0-00ed-4397-bace-fe90a312ca15-16x12.jpg 16w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/83868ba0-00ed-4397-bace-fe90a312ca15.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/acbfc883-bc7d-4e1b-bd6c-cd337fa78136.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"15557\" src=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/acbfc883-bc7d-4e1b-bd6c-cd337fa78136-1024x768.jpg\" alt=\"\" class=\"wp-image-15557\" srcset=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/acbfc883-bc7d-4e1b-bd6c-cd337fa78136-1024x768.jpg 1024w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/acbfc883-bc7d-4e1b-bd6c-cd337fa78136-300x225.jpg 300w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/acbfc883-bc7d-4e1b-bd6c-cd337fa78136-768x576.jpg 768w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/acbfc883-bc7d-4e1b-bd6c-cd337fa78136-1536x1152.jpg 1536w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/acbfc883-bc7d-4e1b-bd6c-cd337fa78136-16x12.jpg 16w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/acbfc883-bc7d-4e1b-bd6c-cd337fa78136.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/cf0141d2-1656-4fa2-a370-b30d84bcf721.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"15565\" src=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/cf0141d2-1656-4fa2-a370-b30d84bcf721-768x1024.jpg\" alt=\"\" class=\"wp-image-15565\" srcset=\"https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/cf0141d2-1656-4fa2-a370-b30d84bcf721-768x1024.jpg 768w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/cf0141d2-1656-4fa2-a370-b30d84bcf721-225x300.jpg 225w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/cf0141d2-1656-4fa2-a370-b30d84bcf721-1152x1536.jpg 1152w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/cf0141d2-1656-4fa2-a370-b30d84bcf721-9x12.jpg 9w, https:\/\/spsow.cz\/wp-content\/uploads\/2026\/05\/cf0141d2-1656-4fa2-a370-b30d84bcf721.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n<\/figure>","protected":false},"excerpt":{"rendered":"<p>V r\u00e1mci 27. ro\u010dn\u00edku festivalu N\u00e1chodsk\u00e1 prima sez\u00f3na prob\u011bhla v\u00fdtvarn\u00e1 sout\u011b\u017e \u201ePod lupou\u201c, kter\u00e1 hledala kr\u00e1su v detailech a skryt\u00fdch v\u00fdznamech sv\u011bta kolem n\u00e1s. Na\u0161e studentky 2. ro\u010dn\u00edku oboru Grafick\u00fd design v&nbsp;kategorii st\u0159edo\u0161kol\u00e1k\u016f (16\u201318 let) zaz\u00e1\u0159ily a odnesly si v\u0161echna t\u0159i nejvy\u0161\u0161\u00ed ocen\u011bn\u00ed. V\u0161echna sout\u011b\u017en\u00ed d\u00edla, kter\u00e1 zkoumaj\u00ed t\u00e9mata jako [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":15556,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-15538","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-4"],"_links":{"self":[{"href":"https:\/\/spsow.cz\/en\/wp-json\/wp\/v2\/posts\/15538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spsow.cz\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spsow.cz\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spsow.cz\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/spsow.cz\/en\/wp-json\/wp\/v2\/comments?post=15538"}],"version-history":[{"count":1,"href":"https:\/\/spsow.cz\/en\/wp-json\/wp\/v2\/posts\/15538\/revisions"}],"predecessor-version":[{"id":15567,"href":"https:\/\/spsow.cz\/en\/wp-json\/wp\/v2\/posts\/15538\/revisions\/15567"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spsow.cz\/en\/wp-json\/wp\/v2\/media\/15556"}],"wp:attachment":[{"href":"https:\/\/spsow.cz\/en\/wp-json\/wp\/v2\/media?parent=15538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spsow.cz\/en\/wp-json\/wp\/v2\/categories?post=15538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spsow.cz\/en\/wp-json\/wp\/v2\/tags?post=15538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}